{"id":14177,"date":"2017-10-16T12:00:00","date_gmt":"2017-10-16T10:00:00","guid":{"rendered":"https:\/\/shamengo.com\/pionnier\/243-laurent-goudet\/"},"modified":"2018-09-13T16:07:31","modified_gmt":"2018-09-13T14:07:31","slug":"243-laurent-goudet","status":"publish","type":"project","link":"https:\/\/www.shamengo.com\/fr\/pionnier\/243-laurent-goudet\/","title":{"rendered":"Je construis des maisons en b\u00e9ton v\u00e9g\u00e9tal"},"content":{"rendered":"<div class=\"woocommerce\">\n<div class=\"woocommerce-info wc-memberships-restriction-message wc-memberships-message wc-memberships-content-restricted-message\">To access this content, you must purchase <span class=\"wc-memberships-products-grant-access\"><a href=\"https:\/\/www.shamengo.com\/fr\/produit\/kit-dinitiation\/\">Cycle d&#8217;initiation<\/a><\/span>, or <a href=\"https:\/\/www.shamengo.com\/fr\/?page_id=38\">log in<\/a> if you are a member.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"woocommerce\">\n<div class=\"woocommerce-info wc-memberships-restriction-message wc-memberships-message wc-memberships-content-restricted-message\">To access this content, you must purchase <span class=\"wc-memberships-products-grant-access\"><a href=\"https:\/\/www.shamengo.com\/fr\/produit\/kit-dinitiation\/\">Cycle d&#8217;initiation<\/a><\/span>, or <a href=\"https:\/\/www.shamengo.com\/fr\/?page_id=38\">log in<\/a> if you are a member.<\/div>\n<\/div>\n","protected":false},"author":9298,"featured_media":17925,"comment_status":"closed","ping_status":"closed","template":"","project_state":[696],"project_tag":[],"country":[3171],"thematique":[3577,3083],"class_list":["post-14177","project","type-project","status-publish","has-post-thumbnail","hentry","project_state-commercialise-diffuse","country-fr-fr","thematique-preservation-de-la-biodiversite","thematique-reduction-de-la-pollution","membership-content","access-restricted"],"acf":{"project_state":696,"project_behind_the_scene":"<p class=\"p1\"><span class=\"s1\">Pour retrouver la trace de Laurent, inutile d&rsquo;arpenter les plateaux t&eacute;l&eacute; ou de fr&eacute;quenter les cercles de r&eacute;flexion sur le monde de demain, il vaut mieux chausser ses bottes et ne pas craindre la poussi&egrave;re des chantiers. Laurent est un bosseur acharn&eacute;, passionn&eacute; par par toutes les techniques de construction &eacute;cologiques, dont bien &eacute;videmment le b&eacute;ton v&eacute;g&eacute;tal. C&rsquo;est aussi un fin lettr&eacute; qui aime transmettre son immense savoir. Il a juste besoin de se faire connaitre&hellip;et nous sommes ravis d&rsquo;y contribuer !<\/span><\/p>","project_country_infos":"","project_location":{"address":"56150 Baud, France","lat":"47.8740630","lng":"-3.0214040"},"project_website":"http:\/\/www.akta-bvp.com\/","project_address":"baud","project_main_thematique":190,"health_thematic_percent":false,"ethics_thematic_percent":false,"environment_thematic_percent":true,"social_thematic_percent":false,"project_thematique":[3577,3083],"project_country":3171,"project_cover_image":38002,"project_video_link":"14549","project_city":"baud","project_title":"Je construis des maisons en b\u00e9ton v\u00e9g\u00e9tal","project_description":"<p class=\"p1\"><span class=\"s1\">Saviez-vous que 75% des plages de la plan\u00e8te sont en train de disparaitre afin de b\u00e9tonner nos villes ? Saviez-vous \u00e9galement que l\u2019on peut remplacer le sable utilis\u00e9 dans la construction par des fibres v\u00e9g\u00e9tales comme le chanvre ? Si vous le d\u00e9couvrez\u2026nous vous invitons \u00e0 regarder le portrait de Laurent Goudet qui d\u00e9veloppe depuis 30 ans un mat\u00e9riau \u00e9cologique aux performances thermiques exceptionnelles. Forc\u00e9ment b\u00e9ton !<\/span><\/p>\n","display_project_contributions_in_front":false,"project_creation_date":"","is_top_project":true,"is_head_project":false,"project_stopped_state_reason":"","project_pdf":false,"project_shooting_date":"","project_gallery":"37948","project_company_name":"","project_commercial_name":"","project_simple_name":"","project_author_notes":"","redacteur":""},"custom-fields":{"authorname":"Laurent Goudet","thumbnail":"\/\/www.shamengo.com\/wp-content\/uploads\/2017\/10\/7874.jpg","project_cover_image":"\/\/www.shamengo.com\/wp-content\/uploads\/2017\/10\/Laurent-Goudet.jpg"},"_links":{"self":[{"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/project\/14177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/users\/9298"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/comments?post=14177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/media\/17925"}],"wp:attachment":[{"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/media?parent=14177"}],"wp:term":[{"taxonomy":"project_state","embeddable":true,"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/project_state?post=14177"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/project_tag?post=14177"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/country?post=14177"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.shamengo.com\/fr\/wp-json\/wp\/v2\/thematique?post=14177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}